{"id":35785,"date":"2023-12-27T01:01:00","date_gmt":"2023-12-27T04:01:00","guid":{"rendered":"https:\/\/caravanagrupoeditorial.com\/?p=35785"},"modified":"2026-02-09T17:01:40","modified_gmt":"2026-02-09T20:01:40","slug":"desjardim-um-romance-neopicaresco","status":"publish","type":"post","link":"https:\/\/caravanagrupoeditorial.com\/es_cl\/desjardim-um-romance-neopicaresco\/","title":{"rendered":"Desjardim, um romance neopicaresco"},"content":{"rendered":"<p style=\"text-align: justify;\">Autor de vast\u00edssima obra, Silas Corr\u00eaa Leite (1952) volta a publicar e contempla agora leitores com um romance que pode ser considerado n\u00e3o s\u00f3 uma par\u00e1bola da condi\u00e7\u00e3o humana como um genu\u00edno exemplo de literatura neopicaresca brasileira, vertente liter\u00e1ria assim nomeada pelo escritor argentino-brasileiro Mario Miguel Gonz\u00e1lez (1937\u20132013), que foi professor de Literaturas Espanhola e Hispano-americana na Faculdade de Filosofia, Letras e Ci\u00eancias Humanas (FFLCH), da Universidade de S\u00e3o Paulo (USP), e  mestre de gera\u00e7\u00f5es de hispanistas e professores de espanhol.<\/br> \n<\/br>\nDe fato, Desjardim \u2014 muito al\u00e9m do farol do fim do mundo (Belo Horizonte, Editora Caravana, 2023) \u00e9 um romance que surpreende por sua pouca linearidade e que, ao tra\u00e7ar a trajet\u00f3ria de um marginalizado brasileiro, recomp\u00f5e um personagem que faz lembrar Lazarillo de Tormes, de autor an\u00f4nimo, e Guzm\u00e1n de Alfarache, de Mateo Alem\u00e1n (1547\u20131614), \u00edcones do primeiro e do segundo \u201cs\u00e9culo de ouro\u201d espanhol, que inclui o XVI, do reinado de Felipe II (1527\u20131598), que foi rei de Espanha (1556\u20131598) e de Portugal e Algarves (1580\u20131598), e boa parte do XVII, que s\u00e3o marcados por um conceito unificador: o barroco.<\/br>\n<\/br>\nSegundo o cr\u00edtico espanhol Miguel Herrero Garc\u00eda (1895\u20131961), em Nueva interpretaci\u00f3n de la novela picaresca (1937), estas novelas n\u00e3o s\u00e3o mais que autobiografias ou confiss\u00f5es de pecadores escarmentados (ou seja, castigados), no sentido religioso por serem vistos como culpados por afrontarem a propriedade ou bens alheios, mas essa defini\u00e7\u00e3o n\u00e3o chega a ser globalizante, sendo mais aceit\u00e1vel aquela que o hispanista ingl\u00eas Alexander A. Parker (1908\u20131989) cunhou, a de delinquente, como se pode constatar em Literature and the delinquent (Edinburgh University Press, 1969), no sentido daquele que avan\u00e7a contra a moral e as leis vigentes, um ser sem honra e antissocial, mas n\u00e3o um gangster ou um assassino. No Brasil e em Portugal, o p\u00edcaro passou a ser aquela pessoa vil e astuta que vive de expedientes, transitando entre as v\u00e1rias classes sociais, um despossu\u00eddo que com arte e dissimula\u00e7\u00e3o obt\u00e9m o que deseja.<\/br>\n<\/br>\nAqui, por\u00e9m, o que se deve levar em conta \u00e9 que muitas dessas pessoas acabavam por tomar essa trilha porque seriam v\u00edtimas de uma ordem social injusta. No caso do \u201cs\u00e9culo de ouro\u201d espanhol, era uma \u00e9poca em que n\u00e3o havia sequer burguesia, ou seja, uns poucos nobres dominavam tudo, enquanto a maioria de dominados s\u00f3 tinha como sa\u00edda legal para a sobreviv\u00eancia submeter-se a um trabalho servil, an\u00e1logo \u00e0 escravid\u00e3o. Mutatis mutandis, o Brasil de hoje n\u00e3o difere muito da Espanha daqueles anos abordados pela literatura picaresca, j\u00e1 que at\u00e9 h\u00e1 pouco tempo, por exemplo, os super-ricos n\u00e3o tinham sequer suas vastas rendas taxadas, enquanto multid\u00f5es de fam\u00e9licos enxameiam as ruas das grandes e pequenas cidades em busca de um prato de comida.<\/br>\n<\/br>\nPois bem, o personagem principal deste novo livro de Silas Corr\u00eaa Leite, que completa uma trilogia que come\u00e7ou a ser projetada em 1995, reunindo Ele est\u00e1 no meio de n\u00f3s (2018) e O Marceneiro \u2014 a \u00faltima tentativa de Cristo (2019), \u00e9 um delinquente, que, com os devidos descontos, pode ser tamb\u00e9m considerado um p\u00edcaro. Em outras palavras: o romance conta a tumultuada trajet\u00f3ria de vida de um jovem que come\u00e7ou pelo lado errado, ao aceitar participar de um assalto \u00e0 m\u00e3o armada em uma ag\u00eancia banc\u00e1ria na cidade de S\u00e3o Paulo, o que acabaria por se tornar uma trag\u00e9dia familiar.<\/br>\n<\/br>\nDepois do crime consumado, o jovem meliante foge como querendo esquecer o mau passo dado e voltar ao come\u00e7o da louca jornada da vida que escolheu e fazer tudo diferente. Mas quando n\u00e3o h\u00e1 uma sa\u00edda, nada faz a volta ser pac\u00edfica. No meio do caminho do desespero, h\u00e1 ainda um palha\u00e7o negro vestindo um macac\u00e3o amarelo, com um botij\u00e3o de g\u00e1s nos ombros largos, como um acusador e modificador de roteiro, feito um juiz e salvador no limbo das circunst\u00e2ncias. Em poucas palavras: trata-se de um livro sobre medo, fuga, arrependimento, culpa e castigo, crime e acusa\u00e7\u00e3o. Afinal, o que vem para salvar tamb\u00e9m pode cobrar seu pre\u00e7o.<\/br>\n<\/br>\nTal como os dois livros anteriores, tamb\u00e9m este pode ser definido como m\u00edstico, ecum\u00eanico e religioso \u2014 e, por isso, mesmo pol\u00eamico \u2014, al\u00e9m de prof\u00e9tico, ao anunciar um caos apocal\u00edptico que parece se consumar nos dias de hoje. E, nesse sentido, segue as caracter\u00edsticas principais da literatura picaresca espanhola, ainda que n\u00e3o se trate de uma autobiografia.<\/br>\n<\/br>\nSeja como for, embora narrado em terceira pessoa, n\u00e3o deixa de seguir o processo que se constata em Lazarillo de Tormes e Guzm\u00e1n de Alfarache, ou seja, h\u00e1 um olhar de fora da sociedade, que condena as injusti\u00e7as e iniquidades que os donos do poder cometem, mas que, ao mesmo tempo, deixa entrever que, se pudesse, o personagem tamb\u00e9m haveria de agir como aqueles que mandam. Melhor dizendo, o que o p\u00edcaro quer \u00e9 ser aceito por aquela sociedade que o refuta e repele. \u201cAssim, seu \u00fanico objetivo como p\u00edcaro \u00e9 deixar de s\u00ea-lo\u201d, como bem observa o professor, ensa\u00edsta, poeta e tradutor espanhol Jenaro Tal\u00e9ns (1946) em Novela picaresca y pr\u00e1ctica de la transgresi\u00f3n (Madrid, Ediciones Jucar, 1975).<\/br>\n<\/br>\nUm resumo do livro pode ser lido nas pr\u00f3prias palavras do autor, quando faz um retrato de seu personagem, antes dele conhecer Ver\u00f4nica, a filha de um vigarista bem sucedido, que haveria de se apaixonar por ele: \u201c(\u2026) Rafael, em abstin\u00eancia aqui e ali, do errado percurso, tivera que, na marra \u2014 ou instinto? \u2014 se livrar do crack, e, malemal se cuidando, ter um bizarro \u201csurto\u201d de planejar e tentar um maldito assalto a banco que falhara. Era muito para a cabe\u00e7a dele. Fugindo de seu passado, morara na rua, em Sampa, o pior lugar do continente para se morar na rua. A rua \u00e9 um livro aberto. Sem rosto, sem navalha como cart\u00e3o de cr\u00e9dito, como dizia uma letra de rock, dormira embaixo de pontes, sob viadutos fara\u00f4nicos e esta\u00e7\u00f5es do Metro superfaturadas por corruptos neoliberais, e conhecia muito bem os meandros dos subterr\u00e2neos da cidade ref\u00e9m do narcocontrabando informal; da Rua 25 de Mar\u00e7o \u00e0 Avenida Paulista. Conhecia os podres subterr\u00e2neos do Carandiru \u00e0 Cracol\u00e2ndia, das privatiza\u00e7\u00f5es-roubos (privatarias) \u00e0s m\u00e1fias e quadrilhas neoliberais que governavam os governos, numa corrup\u00e7\u00e3o end\u00eamica institucionalizada e uma impunidade generalizada em todos os n\u00edveis, tudo blindado por parte da m\u00eddia abutre amoral atrelada com seus agiotas emboabas, e s\u00f3 ele sabia quanto faria bem voltar para casa, mesmo que doesse essa volta\u201d.  (p\u00e1g. 83).<\/br>\nEis um retrato de um Brasil que quase nunca aparece nas p\u00e1ginas dos agonizantes jornais impressos de hoje ou mesmo nos sites das organiza\u00e7\u00f5es que ainda os mant\u00e9m que  pode ser visto tamb\u00e9m aqui neste trecho: \u201c(\u2026) Nesse \u00ednterim, souberam que o pai de Ver\u00f4nica ajuntara uma baita grana de fundo falso e suspeito (as m\u00e1fias de S\u00e3o Paulo; M\u00e1fia do Lixo, do Transporte P\u00fablico, do Metro, das Pra\u00e7as de Ped\u00e1gio, da Merenda, da Sa\u00fade P\u00fablica propositalmente sucateada, do insano e amoral c\u00ednico estado m\u00ednimo \u2014 a moderniza\u00e7\u00e3o do atraso; o estado mais rico do Brasil, talvez tamb\u00e9m fosse o estado mais corrupto do Brasil), e por essas e outras falcatruas em bando, o velhote fugira com a filha Valk\u00edria para algum lugar perto da Su\u00ed\u00e7a, visando ali se esconder da justi\u00e7a e tamb\u00e9m dos cobradores bandidos e corruptos neoliberais de Bras\u00edlia, amigos do alheio no er\u00e1rio p\u00fablico, e de impunes gangues de privatarias (privatiza\u00e7\u00f5es-roubos) de Samparaguai, como dizia. O entregador de g\u00e1s sabia de lucros impunes, riquezas injustas (como narrou S\u00e3o Lucas), propriedades roubos, o pr\u00f3prio neoescravismo da terceiriza\u00e7\u00e3o e da necropol\u00edtica, e pensava como Roberto Bola\u00f1o: \u201cA Am\u00e9rica Latina foi o manic\u00f4mio da Europa, assim como os Estados Unidos foram a sua f\u00e1brica. A f\u00e1brica agora est\u00e1 em poder dos capatazes, e loucos fugidos s\u00e3o sua m\u00e3o de obra. O manic\u00f4mio est\u00e1 queimando o seu pr\u00f3prio \u00f3leo\u201d. (p\u00e1g. 135).<\/br>\n<\/br>\nOutro personagem marcante \u00e9 o Advogado Dr. Sabe Tudo, de nome Ely, que trata de livrar Rafael das m\u00e3os da Justi\u00e7a e que, para conhecer melhor seu cliente, faz uma viagem \u00e0 cidade natal dele, a Santa Itarar\u00e9 das Artes, capital art\u00edstica-cultural da regi\u00e3o sudoeste do Estado de S\u00e3o Paulo, j\u00e1 na divisa com o Paran\u00e1, por coincid\u00eancia (ou n\u00e3o?) tamb\u00e9m terra em que cresceu o autor. E, ao faz\u00ea-lo, acabou por conhecer (e ajudar) \u201cos fracos e oprimidos da periferia de descamisados da cidade, compostos por exclu\u00eddos sociais, polacos oriundos do \u00eaxodo rural, do noroeste do vizinho estado do Paran\u00e1, com a agricultura mecanizada e com t\u00e9cnicas modernas refugando seus homens humildes do campo\u201d. Com isso, o leitor, acostumado a ver apenas pretos e miscigenados como maioria entre os exclu\u00eddos, vai descobrir que, muitas vezes, a busca do lucro f\u00e1cil em riquezas impunes tamb\u00e9m pode produzir hordas de descal\u00e7ados de pele mais clara.<\/br>\n<\/br>\nPor aqui se v\u00ea que este \u00e9 um romance que foge um pouco \u00e0 linearidade que se nota nos \u00faltimos produtos do g\u00eanero, exibindo m\u00faltiplas linguagens e intertextos, pois procura, ao denunciar as injusti\u00e7as de uma sociedade de desiguais, reproduzir a fala comum entre as massas de fam\u00e9licos e remediados. E segue uma vertente neopicaresca de nossa literatura que inclui entre os seus precursores Manuel Ant\u00f4nio de Almeida (1831\u20131861), com Mem\u00f3rias de um sargento de mil\u00edcias (1852), M\u00e1rio de Andrade (1893\u20131945), com Macuna\u00edma (1928), e, mais recentemente, Marcos Rey (1925\u20131999), com Mem\u00f3rias de um gigol\u00f4 (1968), obras que re\u00fanem anti-her\u00f3is, que receberam a denomina\u00e7\u00e3o de neop\u00edcaros do professor e cr\u00edtico Mario Miguel Gonz\u00e1lez e de malandros do professor e cr\u00edtico Ant\u00f4nio C\u00e2ndido (1918\u20132017). Nesse caso, como observou Gonz\u00e1lez, neop\u00edcaros e malandros seriam sin\u00f4nimos.<\/br>\n<\/br>\nQuanto ao t\u00edtulo do livro, o pr\u00f3prio autor \u00e9 quem o bem define, ao observar que \u201cmuito al\u00e9m do farol do mundo\u201d \u00e9 uma express\u00e3o que abarca qualquer lugar, em que \u201cqualquer um pode ser posto \u00e0 prova em ju\u00edzo de confinamento, jugo e valor\u201d. Um leitmotiv que conduz para uma ideia de travessia, deslocamentos e retorno sem fim.\n<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"720\" src=\"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/12\/desjardim.jpg?resize=720%2C720&#038;ssl=1\" alt=\"\" class=\"wp-image-35786 size-full\" srcset=\"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/12\/desjardim.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/12\/desjardim.jpg?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/12\/desjardim.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/12\/desjardim.jpg?resize=510%2C510&amp;ssl=1 510w, https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/12\/desjardim.jpg?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/12\/desjardim.jpg?resize=64%2C64&amp;ssl=1 64w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Adelto Gon\u00e7alves \u00e9 doutor em Letras na \u00e1rea de Literatura Portuguesa pela USP e autor de <em>Gonzaga, um Poeta do Iluminismo<\/em> (Rio de Janeiro, Nova Fronteira, 1999), <em>Barcelona Brasileira<\/em> (Lisboa, Nova Arrancada, 1999; S\u00e3o Paulo, Publisher Brasil, 2002), <em>Fernando Pessoa: a Voz de Deus<\/em> (Santos, Editora da Unisanta, 1997), <em>Bocage \u2014 o Perfil Perdido<\/em> (Lisboa, Caminho, 2003; S\u00e3o Paulo, Imprensa Oficial do Estado de S\u00e3o Paulo: Imesp, 2021), <em>Tom\u00e1s Ant\u00f4nio Gonzaga<\/em> (Imesp\/Academia Brasileira de Letras, 2012),\u00a0 <em>Direito e Justi\u00e7a em Terras d\u00b4El-Rei na S\u00e3o Paulo Colonia l<\/em> (Imesp, 2015), <em>Os Vira-latas da Madrugada<\/em> (Rio de Janeiro, Livraria Jos\u00e9 Olympio Editora, 1981; Taubat\u00e9-SP, Letra Selvagem, 2015), <em>O Reino, a Col\u00f4nia e o Poder: o governo Lorena na capitania de S\u00e3o Paulo \u2014 1788\u20131797<\/em> (Imesp, 2019), entre outros.<\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Autor de vast\u00edssima obra, Silas Corr\u00eaa Leite (1952) volta a publicar e contempla agora leitores com um romance que pode ser considerado n\u00e3o s\u00f3 uma par\u00e1bola da condi\u00e7\u00e3o humana como<\/p>","protected":false},"author":1,"featured_media":35788,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[20603,193],"tags":[],"class_list":["post-35785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronicas-editoriais","category-sem-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Desjardim, um romance neopicaresco - Caravana Grupo Editorial<\/title>\n<meta name=\"description\" content=\"Na \u00faltima FLIP (novembro de 2023) participei da mesa que fez bastante sucesso. A quest\u00e3o era: Como nasce um romance? Esta \u00e9 uma pergunta que nos leva aos tantos mist\u00e9rios que a vida engloba. Com o livro pronto, o pr\u00f3prio autor j\u00e1 n\u00e3o se lembra das pequenas inspira\u00e7\u00f5es que o envolveram para que criasse cada momento da hist\u00f3ria. Como escrevo romances policiais, come\u00e7o criando uma estrutura de come\u00e7o, meio e fim ou crime, investiga\u00e7\u00e3o e solu\u00e7\u00e3o. Pego um fato real, que seleciono entre as tantas trag\u00e9dias que s\u00e3o noticiadas pela m\u00eddia, e parto para a fic\u00e7\u00e3o. Da\u00ed, qualquer semelhan\u00e7a com a realidade \u00e9 mera coincid\u00eancia. Quando monto a estrutura, o que preciso saber \u00e9 o que o leitor vai perguntar durante toda a leitura: Quem \u00e9 o assassino(a)? Eu, como autora, tenho de saber quem matou para ir levando a hist\u00f3ria nessa dire\u00e7\u00e3o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/caravanagrupoeditorial.com\/es_cl\/desjardim-um-romance-neopicaresco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desjardim, um romance neopicaresco - Caravana Grupo Editorial\" \/>\n<meta property=\"og:description\" content=\"Na \u00faltima FLIP (novembro de 2023) participei da mesa que fez bastante sucesso. A quest\u00e3o era: Como nasce um romance? Esta \u00e9 uma pergunta que nos leva aos tantos mist\u00e9rios que a vida engloba. Com o livro pronto, o pr\u00f3prio autor j\u00e1 n\u00e3o se lembra das pequenas inspira\u00e7\u00f5es que o envolveram para que criasse cada momento da hist\u00f3ria. Como escrevo romances policiais, come\u00e7o criando uma estrutura de come\u00e7o, meio e fim ou crime, investiga\u00e7\u00e3o e solu\u00e7\u00e3o. Pego um fato real, que seleciono entre as tantas trag\u00e9dias que s\u00e3o noticiadas pela m\u00eddia, e parto para a fic\u00e7\u00e3o. Da\u00ed, qualquer semelhan\u00e7a com a realidade \u00e9 mera coincid\u00eancia. Quando monto a estrutura, o que preciso saber \u00e9 o que o leitor vai perguntar durante toda a leitura: Quem \u00e9 o assassino(a)? Eu, como autora, tenho de saber quem matou para ir levando a hist\u00f3ria nessa dire\u00e7\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/caravanagrupoeditorial.com\/es_cl\/desjardim-um-romance-neopicaresco\/\" \/>\n<meta property=\"og:site_name\" content=\"Caravana Grupo Editorial\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/caravanagrupoeditorial\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-27T04:01:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T20:01:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/12\/desjardimmailer-1.png?fit=1080%2C1080&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Web Designer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Web Designer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/desjardim-um-romance-neopicaresco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/desjardim-um-romance-neopicaresco\\\/\"},\"author\":{\"name\":\"Web Designer\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#\\\/schema\\\/person\\\/abf39d87b39b20bc7acbebdea985becc\"},\"headline\":\"Desjardim, um romance neopicaresco\",\"datePublished\":\"2023-12-27T04:01:00+00:00\",\"dateModified\":\"2026-02-09T20:01:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/desjardim-um-romance-neopicaresco\\\/\"},\"wordCount\":1908,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/desjardim-um-romance-neopicaresco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/desjardimmailer-1.png?fit=1080%2C1080&ssl=1\",\"articleSection\":[\"Cr\u00f4nicas editoriais\",\"Sem categoria\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/caravanagrupoeditorial.com\\\/desjardim-um-romance-neopicaresco\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/desjardim-um-romance-neopicaresco\\\/\",\"url\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/desjardim-um-romance-neopicaresco\\\/\",\"name\":\"Desjardim, um romance neopicaresco - Caravana Grupo Editorial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/desjardim-um-romance-neopicaresco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/desjardim-um-romance-neopicaresco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/desjardimmailer-1.png?fit=1080%2C1080&ssl=1\",\"datePublished\":\"2023-12-27T04:01:00+00:00\",\"dateModified\":\"2026-02-09T20:01:40+00:00\",\"description\":\"Na \u00faltima FLIP (novembro de 2023) participei da mesa que fez bastante sucesso. A quest\u00e3o era: Como nasce um romance? Esta \u00e9 uma pergunta que nos leva aos tantos mist\u00e9rios que a vida engloba. Com o livro pronto, o pr\u00f3prio autor j\u00e1 n\u00e3o se lembra das pequenas inspira\u00e7\u00f5es que o envolveram para que criasse cada momento da hist\u00f3ria. Como escrevo romances policiais, come\u00e7o criando uma estrutura de come\u00e7o, meio e fim ou crime, investiga\u00e7\u00e3o e solu\u00e7\u00e3o. Pego um fato real, que seleciono entre as tantas trag\u00e9dias que s\u00e3o noticiadas pela m\u00eddia, e parto para a fic\u00e7\u00e3o. Da\u00ed, qualquer semelhan\u00e7a com a realidade \u00e9 mera coincid\u00eancia. Quando monto a estrutura, o que preciso saber \u00e9 o que o leitor vai perguntar durante toda a leitura: Quem \u00e9 o assassino(a)? Eu, como autora, tenho de saber quem matou para ir levando a hist\u00f3ria nessa dire\u00e7\u00e3o.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/desjardim-um-romance-neopicaresco\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/caravanagrupoeditorial.com\\\/desjardim-um-romance-neopicaresco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/desjardim-um-romance-neopicaresco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/desjardimmailer-1.png?fit=1080%2C1080&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/desjardimmailer-1.png?fit=1080%2C1080&ssl=1\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/desjardim-um-romance-neopicaresco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desjardim, um romance neopicaresco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#website\",\"url\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/\",\"name\":\"Caravana Grupo Editorial\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#organization\",\"name\":\"Caravana Grupo Editorial\",\"url\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Logo_Caravana.png\",\"contentUrl\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Logo_Caravana.png\",\"width\":512,\"height\":512,\"caption\":\"Caravana Grupo Editorial\"},\"image\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/caravanagrupoeditorial\",\"https:\\\/\\\/www.instagram.com\\\/caravanagrupoeditorial\\\/?hl=pt-br\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCdD-xosEkpHCeRn2nDLiXfQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#\\\/schema\\\/person\\\/abf39d87b39b20bc7acbebdea985becc\",\"name\":\"Web Designer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g\",\"caption\":\"Web Designer\"},\"sameAs\":[\"https:\\\/\\\/caravanagrupoeditorial.com\"],\"url\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/es_cl\\\/author\\\/caravanagrupoedi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desjardim, um romance neopicaresco - Caravana Grupo Editorial","description":"Na \u00faltima FLIP (novembro de 2023) participei da mesa que fez bastante sucesso. A quest\u00e3o era: Como nasce um romance? Esta \u00e9 uma pergunta que nos leva aos tantos mist\u00e9rios que a vida engloba. Com o livro pronto, o pr\u00f3prio autor j\u00e1 n\u00e3o se lembra das pequenas inspira\u00e7\u00f5es que o envolveram para que criasse cada momento da hist\u00f3ria. Como escrevo romances policiais, come\u00e7o criando uma estrutura de come\u00e7o, meio e fim ou crime, investiga\u00e7\u00e3o e solu\u00e7\u00e3o. Pego um fato real, que seleciono entre as tantas trag\u00e9dias que s\u00e3o noticiadas pela m\u00eddia, e parto para a fic\u00e7\u00e3o. Da\u00ed, qualquer semelhan\u00e7a com a realidade \u00e9 mera coincid\u00eancia. Quando monto a estrutura, o que preciso saber \u00e9 o que o leitor vai perguntar durante toda a leitura: Quem \u00e9 o assassino(a)? Eu, como autora, tenho de saber quem matou para ir levando a hist\u00f3ria nessa dire\u00e7\u00e3o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/caravanagrupoeditorial.com\/es_cl\/desjardim-um-romance-neopicaresco\/","og_locale":"es_ES","og_type":"article","og_title":"Desjardim, um romance neopicaresco - Caravana Grupo Editorial","og_description":"Na \u00faltima FLIP (novembro de 2023) participei da mesa que fez bastante sucesso. A quest\u00e3o era: Como nasce um romance? Esta \u00e9 uma pergunta que nos leva aos tantos mist\u00e9rios que a vida engloba. Com o livro pronto, o pr\u00f3prio autor j\u00e1 n\u00e3o se lembra das pequenas inspira\u00e7\u00f5es que o envolveram para que criasse cada momento da hist\u00f3ria. Como escrevo romances policiais, come\u00e7o criando uma estrutura de come\u00e7o, meio e fim ou crime, investiga\u00e7\u00e3o e solu\u00e7\u00e3o. Pego um fato real, que seleciono entre as tantas trag\u00e9dias que s\u00e3o noticiadas pela m\u00eddia, e parto para a fic\u00e7\u00e3o. Da\u00ed, qualquer semelhan\u00e7a com a realidade \u00e9 mera coincid\u00eancia. Quando monto a estrutura, o que preciso saber \u00e9 o que o leitor vai perguntar durante toda a leitura: Quem \u00e9 o assassino(a)? Eu, como autora, tenho de saber quem matou para ir levando a hist\u00f3ria nessa dire\u00e7\u00e3o.","og_url":"https:\/\/caravanagrupoeditorial.com\/es_cl\/desjardim-um-romance-neopicaresco\/","og_site_name":"Caravana Grupo Editorial","article_publisher":"https:\/\/www.facebook.com\/caravanagrupoeditorial","article_published_time":"2023-12-27T04:01:00+00:00","article_modified_time":"2026-02-09T20:01:40+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/12\/desjardimmailer-1.png?fit=1080%2C1080&ssl=1","type":"image\/png"}],"author":"Web Designer","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Web Designer","Tiempo estimado de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/caravanagrupoeditorial.com\/desjardim-um-romance-neopicaresco\/#article","isPartOf":{"@id":"https:\/\/caravanagrupoeditorial.com\/desjardim-um-romance-neopicaresco\/"},"author":{"name":"Web Designer","@id":"https:\/\/caravanagrupoeditorial.com\/#\/schema\/person\/abf39d87b39b20bc7acbebdea985becc"},"headline":"Desjardim, um romance neopicaresco","datePublished":"2023-12-27T04:01:00+00:00","dateModified":"2026-02-09T20:01:40+00:00","mainEntityOfPage":{"@id":"https:\/\/caravanagrupoeditorial.com\/desjardim-um-romance-neopicaresco\/"},"wordCount":1908,"commentCount":0,"publisher":{"@id":"https:\/\/caravanagrupoeditorial.com\/#organization"},"image":{"@id":"https:\/\/caravanagrupoeditorial.com\/desjardim-um-romance-neopicaresco\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/12\/desjardimmailer-1.png?fit=1080%2C1080&ssl=1","articleSection":["Cr\u00f4nicas editoriais","Sem categoria"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/caravanagrupoeditorial.com\/desjardim-um-romance-neopicaresco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/caravanagrupoeditorial.com\/desjardim-um-romance-neopicaresco\/","url":"https:\/\/caravanagrupoeditorial.com\/desjardim-um-romance-neopicaresco\/","name":"Desjardim, um romance neopicaresco - Caravana Grupo Editorial","isPartOf":{"@id":"https:\/\/caravanagrupoeditorial.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/caravanagrupoeditorial.com\/desjardim-um-romance-neopicaresco\/#primaryimage"},"image":{"@id":"https:\/\/caravanagrupoeditorial.com\/desjardim-um-romance-neopicaresco\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/12\/desjardimmailer-1.png?fit=1080%2C1080&ssl=1","datePublished":"2023-12-27T04:01:00+00:00","dateModified":"2026-02-09T20:01:40+00:00","description":"Na \u00faltima FLIP (novembro de 2023) participei da mesa que fez bastante sucesso. A quest\u00e3o era: Como nasce um romance? Esta \u00e9 uma pergunta que nos leva aos tantos mist\u00e9rios que a vida engloba. Com o livro pronto, o pr\u00f3prio autor j\u00e1 n\u00e3o se lembra das pequenas inspira\u00e7\u00f5es que o envolveram para que criasse cada momento da hist\u00f3ria. Como escrevo romances policiais, come\u00e7o criando uma estrutura de come\u00e7o, meio e fim ou crime, investiga\u00e7\u00e3o e solu\u00e7\u00e3o. Pego um fato real, que seleciono entre as tantas trag\u00e9dias que s\u00e3o noticiadas pela m\u00eddia, e parto para a fic\u00e7\u00e3o. Da\u00ed, qualquer semelhan\u00e7a com a realidade \u00e9 mera coincid\u00eancia. Quando monto a estrutura, o que preciso saber \u00e9 o que o leitor vai perguntar durante toda a leitura: Quem \u00e9 o assassino(a)? Eu, como autora, tenho de saber quem matou para ir levando a hist\u00f3ria nessa dire\u00e7\u00e3o.","breadcrumb":{"@id":"https:\/\/caravanagrupoeditorial.com\/desjardim-um-romance-neopicaresco\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/caravanagrupoeditorial.com\/desjardim-um-romance-neopicaresco\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/caravanagrupoeditorial.com\/desjardim-um-romance-neopicaresco\/#primaryimage","url":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/12\/desjardimmailer-1.png?fit=1080%2C1080&ssl=1","contentUrl":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/12\/desjardimmailer-1.png?fit=1080%2C1080&ssl=1","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/caravanagrupoeditorial.com\/desjardim-um-romance-neopicaresco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/caravanagrupoeditorial.com\/"},{"@type":"ListItem","position":2,"name":"Desjardim, um romance neopicaresco"}]},{"@type":"WebSite","@id":"https:\/\/caravanagrupoeditorial.com\/#website","url":"https:\/\/caravanagrupoeditorial.com\/","name":"Cat\u00e1logo - Alicanto Editorial","description":"","publisher":{"@id":"https:\/\/caravanagrupoeditorial.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/caravanagrupoeditorial.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/caravanagrupoeditorial.com\/#organization","name":"Cat\u00e1logo - Alicanto Editorial","url":"https:\/\/caravanagrupoeditorial.com\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/caravanagrupoeditorial.com\/#\/schema\/logo\/image\/","url":"https:\/\/caravanagrupoeditorial.com\/wp-content\/uploads\/2024\/02\/cropped-Logo_Caravana.png","contentUrl":"https:\/\/caravanagrupoeditorial.com\/wp-content\/uploads\/2024\/02\/cropped-Logo_Caravana.png","width":512,"height":512,"caption":"Caravana Grupo Editorial"},"image":{"@id":"https:\/\/caravanagrupoeditorial.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/caravanagrupoeditorial","https:\/\/www.instagram.com\/caravanagrupoeditorial\/?hl=pt-br","https:\/\/www.youtube.com\/channel\/UCdD-xosEkpHCeRn2nDLiXfQ"]},{"@type":"Person","@id":"https:\/\/caravanagrupoeditorial.com\/#\/schema\/person\/abf39d87b39b20bc7acbebdea985becc","name":"Web Designer","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g","caption":"Web Designer"},"sameAs":["https:\/\/caravanagrupoeditorial.com"],"url":"https:\/\/caravanagrupoeditorial.com\/es_cl\/author\/caravanagrupoedi\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/12\/desjardimmailer-1.png?fit=1080%2C1080&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/posts\/35785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/comments?post=35785"}],"version-history":[{"count":1,"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/posts\/35785\/revisions"}],"predecessor-version":[{"id":35789,"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/posts\/35785\/revisions\/35789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/media\/35788"}],"wp:attachment":[{"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/media?parent=35785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/categories?post=35785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/tags?post=35785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}