{"id":34924,"date":"2023-11-29T01:41:00","date_gmt":"2023-11-29T04:41:00","guid":{"rendered":"https:\/\/caravanagrupoeditorial.com\/?p=34924"},"modified":"2023-11-28T18:46:45","modified_gmt":"2023-11-28T21:46:45","slug":"como-nasce-o-romance","status":"publish","type":"post","link":"https:\/\/caravanagrupoeditorial.com\/es_cl\/como-nasce-o-romance\/","title":{"rendered":"Como nasce o romance"},"content":{"rendered":"<p style=\"text-align: justify;\">Na \u00faltima FLIP (novembro de 2023) participei da mesa que fez bastante sucesso. A quest\u00e3o era: Como nasce um romance?<\/br>\n<\/br>\nEsta \u00e9 uma pergunta que nos leva aos tantos mist\u00e9rios que a vida engloba. Com o livro pronto, o pr\u00f3prio autor j\u00e1 n\u00e3o se lembra das pequenas inspira\u00e7\u00f5es que o envolveram para que criasse cada momento da hist\u00f3ria. Como escrevo romances policiais, come\u00e7o criando uma estrutura de come\u00e7o, meio e fim ou crime, investiga\u00e7\u00e3o e solu\u00e7\u00e3o. Pego um fato real, que seleciono entre as tantas trag\u00e9dias que s\u00e3o noticiadas pela m\u00eddia, e parto para a fic\u00e7\u00e3o. Da\u00ed, qualquer semelhan\u00e7a com a realidade \u00e9 mera coincid\u00eancia. Quando monto a estrutura, o que preciso saber \u00e9 o que o leitor vai perguntar durante toda a leitura: Quem \u00e9 o assassino(a)? Eu, como autora, tenho de saber quem matou para ir levando a hist\u00f3ria nessa dire\u00e7\u00e3o.<\/br>\n<\/br>\nMas, tentando responder \u00e0 pergunta: como nasce o romance, trago o trecho de um livro que li h\u00e1 algum tempo, de Amoz Oz, escritor que muito admiro. O nome do livro \u00e9 Do que \u00e9 feita a ma\u00e7\u00e3. O livro relata conversas que o autor teve com sua editora. E, falando sobre a escrita, como se \u201cmonta\u201d uma hist\u00f3ria, ele diz: \u201dTome uma ma\u00e7\u00e3. Do que \u00e9 feita a ma\u00e7\u00e3? \u00c1gua, terra, sol, uma macieira e um pouco de adubo. Mas a ma\u00e7\u00e3 n\u00e3o se parece com nenhuma destas coisas. \u00c9 feita delas, mas n\u00e3o se parece com elas. Assim \u00e9 uma hist\u00f3ria que, com certeza, \u00e9 feita de uma soma de encontros, experi\u00eancias, inspira\u00e7\u00f5es e aten\u00e7\u00f5es.\u201d <\/br>\n<\/br>\nDepois de uma hist\u00f3ria pronta \u00e9 dif\u00edcil separar as partes da qual ela \u00e9 feita. Como autora, posso dizer que com o livro editado, vamos nos esquecendo de onde tiramos cada detalhe trabalhado. Nos esquecemos das pessoas reais e fict\u00edcias que nos fizeram imaginar personagens com as quais vamos criando uma intimidade que muitas vezes n\u00e3o temos com pessoas reais. Meu detetive Alyrio Cobra \u00e9 uma mistura de pessoas reais e investigadores da literatura que adquiriu uma personalidade pr\u00f3pria. \u00c9 com ele que tenho longas conversas para decidir que \u201ccrime\u201d vamos investigar!<\/br>\n<\/br>\nDe onde vem a escrita, de onde v\u00eam as hist\u00f3rias? Acredito ser mais um dos tantos mist\u00e9rios da exist\u00eancia. Em geral, vemos nos romances uma vida individual ligar-se a um elemento divino, ou de algum modo sobre-humano, de tal forma que os acontecimentos de uma exist\u00eancia adquirem um significado que os supera e os encanta. Assim tamb\u00e9m o leitor, ao acompanhar o enredo e as situa\u00e7\u00f5es que o romance tece em torno de sua personagem, se encanta, participa desta vida fict\u00edcia e introduz de algum modo sua pr\u00f3pria exist\u00eancia na esfera das experi\u00eancias, dos amores e desamores da personagem. Podemos ent\u00e3o afirmar que a forma\u00e7\u00e3o de nossas hist\u00f3rias \u00e9 mais um dos mist\u00e9rios da exist\u00eancia.<\/br>\n<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"720\" src=\"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/11\/vera.jpg?resize=720%2C720&#038;ssl=1\" alt=\"\" class=\"wp-image-34925 size-full\" srcset=\"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/11\/vera.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/11\/vera.jpg?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/11\/vera.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/11\/vera.jpg?resize=510%2C510&amp;ssl=1 510w, https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/11\/vera.jpg?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/11\/vera.jpg?resize=64%2C64&amp;ssl=1 64w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Vera Carvalho Assump\u00e7\u00e3o criou, em 2003, o detetive particular Alyrio Cobra, e a cidade S\u00e3o Paulo \u00e9 o cen\u00e1rio das tramas de seus romances. Em 2016, a escritora participou da BAN (Buenos Aires Negra) e em 2018, do Porto Alegre Noir, coordenando a mesa \u201cDetetives de fic\u00e7\u00e3o: ontem e hoje\u201d. Em 2019, participou da \u201cQuinta Noir\u201d, na FLIPO\u00c7OS, venceu o Pr\u00eamio Bunkyo de Literatura e participou de \u201cA narrativa policial e as cidades do crime\u201d na Academia Mineira de Letras. Em 2020 e 2023, venceu o Concurso Ecos da Literatura.<\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Na \u00faltima FLIP (novembro de 2023) participei da mesa que fez bastante sucesso. A quest\u00e3o era: Como nasce um romance? Esta \u00e9 uma pergunta que nos leva aos tantos mist\u00e9rios<\/p>","protected":false},"author":1,"featured_media":34926,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[193],"tags":[],"class_list":["post-34924","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como nasce o romance - Caravana Grupo Editorial<\/title>\n<meta name=\"description\" content=\"Na \u00faltima FLIP (novembro de 2023) participei da mesa que fez bastante sucesso. A quest\u00e3o era: Como nasce um romance? Esta \u00e9 uma pergunta que nos leva aos tantos mist\u00e9rios que a vida engloba. Com o livro pronto, o pr\u00f3prio autor j\u00e1 n\u00e3o se lembra das pequenas inspira\u00e7\u00f5es que o envolveram para que criasse cada momento da hist\u00f3ria. Como escrevo romances policiais, come\u00e7o criando uma estrutura de come\u00e7o, meio e fim ou crime, investiga\u00e7\u00e3o e solu\u00e7\u00e3o. Pego um fato real, que seleciono entre as tantas trag\u00e9dias que s\u00e3o noticiadas pela m\u00eddia, e parto para a fic\u00e7\u00e3o. Da\u00ed, qualquer semelhan\u00e7a com a realidade \u00e9 mera coincid\u00eancia. Quando monto a estrutura, o que preciso saber \u00e9 o que o leitor vai perguntar durante toda a leitura: Quem \u00e9 o assassino(a)? Eu, como autora, tenho de saber quem matou para ir levando a hist\u00f3ria nessa dire\u00e7\u00e3o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/caravanagrupoeditorial.com\/es_cl\/como-nasce-o-romance\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como nasce o romance - Caravana Grupo Editorial\" \/>\n<meta property=\"og:description\" content=\"Na \u00faltima FLIP (novembro de 2023) participei da mesa que fez bastante sucesso. A quest\u00e3o era: Como nasce um romance? Esta \u00e9 uma pergunta que nos leva aos tantos mist\u00e9rios que a vida engloba. Com o livro pronto, o pr\u00f3prio autor j\u00e1 n\u00e3o se lembra das pequenas inspira\u00e7\u00f5es que o envolveram para que criasse cada momento da hist\u00f3ria. Como escrevo romances policiais, come\u00e7o criando uma estrutura de come\u00e7o, meio e fim ou crime, investiga\u00e7\u00e3o e solu\u00e7\u00e3o. Pego um fato real, que seleciono entre as tantas trag\u00e9dias que s\u00e3o noticiadas pela m\u00eddia, e parto para a fic\u00e7\u00e3o. Da\u00ed, qualquer semelhan\u00e7a com a realidade \u00e9 mera coincid\u00eancia. Quando monto a estrutura, o que preciso saber \u00e9 o que o leitor vai perguntar durante toda a leitura: Quem \u00e9 o assassino(a)? Eu, como autora, tenho de saber quem matou para ir levando a hist\u00f3ria nessa dire\u00e7\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/caravanagrupoeditorial.com\/es_cl\/como-nasce-o-romance\/\" \/>\n<meta property=\"og:site_name\" content=\"Caravana Grupo Editorial\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/caravanagrupoeditorial\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-29T04:41:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/11\/vera-cronicas.png?fit=1080%2C1080&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Web Designer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Web Designer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/como-nasce-o-romance\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/como-nasce-o-romance\\\/\"},\"author\":{\"name\":\"Web Designer\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#\\\/schema\\\/person\\\/abf39d87b39b20bc7acbebdea985becc\"},\"headline\":\"Como nasce o romance\",\"datePublished\":\"2023-11-29T04:41:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/como-nasce-o-romance\\\/\"},\"wordCount\":590,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/como-nasce-o-romance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/vera-cronicas.png?fit=1080%2C1080&ssl=1\",\"articleSection\":[\"Sem categoria\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/caravanagrupoeditorial.com\\\/como-nasce-o-romance\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/como-nasce-o-romance\\\/\",\"url\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/como-nasce-o-romance\\\/\",\"name\":\"Como nasce o romance - Caravana Grupo Editorial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/como-nasce-o-romance\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/como-nasce-o-romance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/vera-cronicas.png?fit=1080%2C1080&ssl=1\",\"datePublished\":\"2023-11-29T04:41:00+00:00\",\"description\":\"Na \u00faltima FLIP (novembro de 2023) participei da mesa que fez bastante sucesso. A quest\u00e3o era: Como nasce um romance? Esta \u00e9 uma pergunta que nos leva aos tantos mist\u00e9rios que a vida engloba. Com o livro pronto, o pr\u00f3prio autor j\u00e1 n\u00e3o se lembra das pequenas inspira\u00e7\u00f5es que o envolveram para que criasse cada momento da hist\u00f3ria. Como escrevo romances policiais, come\u00e7o criando uma estrutura de come\u00e7o, meio e fim ou crime, investiga\u00e7\u00e3o e solu\u00e7\u00e3o. Pego um fato real, que seleciono entre as tantas trag\u00e9dias que s\u00e3o noticiadas pela m\u00eddia, e parto para a fic\u00e7\u00e3o. Da\u00ed, qualquer semelhan\u00e7a com a realidade \u00e9 mera coincid\u00eancia. Quando monto a estrutura, o que preciso saber \u00e9 o que o leitor vai perguntar durante toda a leitura: Quem \u00e9 o assassino(a)? Eu, como autora, tenho de saber quem matou para ir levando a hist\u00f3ria nessa dire\u00e7\u00e3o.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/como-nasce-o-romance\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/caravanagrupoeditorial.com\\\/como-nasce-o-romance\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/como-nasce-o-romance\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/vera-cronicas.png?fit=1080%2C1080&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/vera-cronicas.png?fit=1080%2C1080&ssl=1\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/como-nasce-o-romance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como nasce o romance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#website\",\"url\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/\",\"name\":\"Caravana Grupo Editorial\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#organization\",\"name\":\"Caravana Grupo Editorial\",\"url\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Logo_Caravana.png\",\"contentUrl\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Logo_Caravana.png\",\"width\":512,\"height\":512,\"caption\":\"Caravana Grupo Editorial\"},\"image\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/caravanagrupoeditorial\",\"https:\\\/\\\/www.instagram.com\\\/caravanagrupoeditorial\\\/?hl=pt-br\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCdD-xosEkpHCeRn2nDLiXfQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#\\\/schema\\\/person\\\/abf39d87b39b20bc7acbebdea985becc\",\"name\":\"Web Designer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g\",\"caption\":\"Web Designer\"},\"sameAs\":[\"https:\\\/\\\/caravanagrupoeditorial.com\"],\"url\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/es_cl\\\/author\\\/caravanagrupoedi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como nasce o romance - Caravana Grupo Editorial","description":"Na \u00faltima FLIP (novembro de 2023) participei da mesa que fez bastante sucesso. A quest\u00e3o era: Como nasce um romance? Esta \u00e9 uma pergunta que nos leva aos tantos mist\u00e9rios que a vida engloba. Com o livro pronto, o pr\u00f3prio autor j\u00e1 n\u00e3o se lembra das pequenas inspira\u00e7\u00f5es que o envolveram para que criasse cada momento da hist\u00f3ria. Como escrevo romances policiais, come\u00e7o criando uma estrutura de come\u00e7o, meio e fim ou crime, investiga\u00e7\u00e3o e solu\u00e7\u00e3o. Pego um fato real, que seleciono entre as tantas trag\u00e9dias que s\u00e3o noticiadas pela m\u00eddia, e parto para a fic\u00e7\u00e3o. Da\u00ed, qualquer semelhan\u00e7a com a realidade \u00e9 mera coincid\u00eancia. Quando monto a estrutura, o que preciso saber \u00e9 o que o leitor vai perguntar durante toda a leitura: Quem \u00e9 o assassino(a)? Eu, como autora, tenho de saber quem matou para ir levando a hist\u00f3ria nessa dire\u00e7\u00e3o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/caravanagrupoeditorial.com\/es_cl\/como-nasce-o-romance\/","og_locale":"es_ES","og_type":"article","og_title":"Como nasce o romance - Caravana Grupo Editorial","og_description":"Na \u00faltima FLIP (novembro de 2023) participei da mesa que fez bastante sucesso. A quest\u00e3o era: Como nasce um romance? Esta \u00e9 uma pergunta que nos leva aos tantos mist\u00e9rios que a vida engloba. Com o livro pronto, o pr\u00f3prio autor j\u00e1 n\u00e3o se lembra das pequenas inspira\u00e7\u00f5es que o envolveram para que criasse cada momento da hist\u00f3ria. Como escrevo romances policiais, come\u00e7o criando uma estrutura de come\u00e7o, meio e fim ou crime, investiga\u00e7\u00e3o e solu\u00e7\u00e3o. Pego um fato real, que seleciono entre as tantas trag\u00e9dias que s\u00e3o noticiadas pela m\u00eddia, e parto para a fic\u00e7\u00e3o. Da\u00ed, qualquer semelhan\u00e7a com a realidade \u00e9 mera coincid\u00eancia. Quando monto a estrutura, o que preciso saber \u00e9 o que o leitor vai perguntar durante toda a leitura: Quem \u00e9 o assassino(a)? Eu, como autora, tenho de saber quem matou para ir levando a hist\u00f3ria nessa dire\u00e7\u00e3o.","og_url":"https:\/\/caravanagrupoeditorial.com\/es_cl\/como-nasce-o-romance\/","og_site_name":"Caravana Grupo Editorial","article_publisher":"https:\/\/www.facebook.com\/caravanagrupoeditorial","article_published_time":"2023-11-29T04:41:00+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/11\/vera-cronicas.png?fit=1080%2C1080&ssl=1","type":"image\/png"}],"author":"Web Designer","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Web Designer","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/caravanagrupoeditorial.com\/como-nasce-o-romance\/#article","isPartOf":{"@id":"https:\/\/caravanagrupoeditorial.com\/como-nasce-o-romance\/"},"author":{"name":"Web Designer","@id":"https:\/\/caravanagrupoeditorial.com\/#\/schema\/person\/abf39d87b39b20bc7acbebdea985becc"},"headline":"Como nasce o romance","datePublished":"2023-11-29T04:41:00+00:00","mainEntityOfPage":{"@id":"https:\/\/caravanagrupoeditorial.com\/como-nasce-o-romance\/"},"wordCount":590,"commentCount":1,"publisher":{"@id":"https:\/\/caravanagrupoeditorial.com\/#organization"},"image":{"@id":"https:\/\/caravanagrupoeditorial.com\/como-nasce-o-romance\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/11\/vera-cronicas.png?fit=1080%2C1080&ssl=1","articleSection":["Sem categoria"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/caravanagrupoeditorial.com\/como-nasce-o-romance\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/caravanagrupoeditorial.com\/como-nasce-o-romance\/","url":"https:\/\/caravanagrupoeditorial.com\/como-nasce-o-romance\/","name":"Como nasce o romance - Caravana Grupo Editorial","isPartOf":{"@id":"https:\/\/caravanagrupoeditorial.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/caravanagrupoeditorial.com\/como-nasce-o-romance\/#primaryimage"},"image":{"@id":"https:\/\/caravanagrupoeditorial.com\/como-nasce-o-romance\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/11\/vera-cronicas.png?fit=1080%2C1080&ssl=1","datePublished":"2023-11-29T04:41:00+00:00","description":"Na \u00faltima FLIP (novembro de 2023) participei da mesa que fez bastante sucesso. A quest\u00e3o era: Como nasce um romance? Esta \u00e9 uma pergunta que nos leva aos tantos mist\u00e9rios que a vida engloba. Com o livro pronto, o pr\u00f3prio autor j\u00e1 n\u00e3o se lembra das pequenas inspira\u00e7\u00f5es que o envolveram para que criasse cada momento da hist\u00f3ria. Como escrevo romances policiais, come\u00e7o criando uma estrutura de come\u00e7o, meio e fim ou crime, investiga\u00e7\u00e3o e solu\u00e7\u00e3o. Pego um fato real, que seleciono entre as tantas trag\u00e9dias que s\u00e3o noticiadas pela m\u00eddia, e parto para a fic\u00e7\u00e3o. Da\u00ed, qualquer semelhan\u00e7a com a realidade \u00e9 mera coincid\u00eancia. Quando monto a estrutura, o que preciso saber \u00e9 o que o leitor vai perguntar durante toda a leitura: Quem \u00e9 o assassino(a)? Eu, como autora, tenho de saber quem matou para ir levando a hist\u00f3ria nessa dire\u00e7\u00e3o.","breadcrumb":{"@id":"https:\/\/caravanagrupoeditorial.com\/como-nasce-o-romance\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/caravanagrupoeditorial.com\/como-nasce-o-romance\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/caravanagrupoeditorial.com\/como-nasce-o-romance\/#primaryimage","url":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/11\/vera-cronicas.png?fit=1080%2C1080&ssl=1","contentUrl":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/11\/vera-cronicas.png?fit=1080%2C1080&ssl=1","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/caravanagrupoeditorial.com\/como-nasce-o-romance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/caravanagrupoeditorial.com\/"},{"@type":"ListItem","position":2,"name":"Como nasce o romance"}]},{"@type":"WebSite","@id":"https:\/\/caravanagrupoeditorial.com\/#website","url":"https:\/\/caravanagrupoeditorial.com\/","name":"Cat\u00e1logo - Alicanto Editorial","description":"","publisher":{"@id":"https:\/\/caravanagrupoeditorial.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/caravanagrupoeditorial.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/caravanagrupoeditorial.com\/#organization","name":"Cat\u00e1logo - Alicanto Editorial","url":"https:\/\/caravanagrupoeditorial.com\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/caravanagrupoeditorial.com\/#\/schema\/logo\/image\/","url":"https:\/\/caravanagrupoeditorial.com\/wp-content\/uploads\/2024\/02\/cropped-Logo_Caravana.png","contentUrl":"https:\/\/caravanagrupoeditorial.com\/wp-content\/uploads\/2024\/02\/cropped-Logo_Caravana.png","width":512,"height":512,"caption":"Caravana Grupo Editorial"},"image":{"@id":"https:\/\/caravanagrupoeditorial.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/caravanagrupoeditorial","https:\/\/www.instagram.com\/caravanagrupoeditorial\/?hl=pt-br","https:\/\/www.youtube.com\/channel\/UCdD-xosEkpHCeRn2nDLiXfQ"]},{"@type":"Person","@id":"https:\/\/caravanagrupoeditorial.com\/#\/schema\/person\/abf39d87b39b20bc7acbebdea985becc","name":"Web Designer","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g","caption":"Web Designer"},"sameAs":["https:\/\/caravanagrupoeditorial.com"],"url":"https:\/\/caravanagrupoeditorial.com\/es_cl\/author\/caravanagrupoedi\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/11\/vera-cronicas.png?fit=1080%2C1080&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/posts\/34924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/comments?post=34924"}],"version-history":[{"count":1,"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/posts\/34924\/revisions"}],"predecessor-version":[{"id":34927,"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/posts\/34924\/revisions\/34927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/media\/34926"}],"wp:attachment":[{"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/media?parent=34924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/categories?post=34924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/tags?post=34924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}