{"id":32852,"date":"2023-11-16T10:22:16","date_gmt":"2023-11-16T13:22:16","guid":{"rendered":"https:\/\/caravanagrupoeditorial.com\/?p=32852"},"modified":"2023-11-16T10:29:53","modified_gmt":"2023-11-16T13:29:53","slug":"morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz","status":"publish","type":"post","link":"https:\/\/caravanagrupoeditorial.com\/es_cl\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\/","title":{"rendered":"Morre, aos 89 anos, a escritora mineira Maria Jos\u00e9 de Queiroz"},"content":{"rendered":"<p style=\"text-align: justify;\">Morreu nesta quarta-feira (15\/11), aos 89 anos, a escritora mineira Maria Jos\u00e9 de Queiroz. O corpo ser\u00e1 velado na Academia Mineira de Letras a partir das 14h. Conhecida pela extensa obra, \u00e9\u00a0autora de mais de 30 t\u00edtulos, incluindo ensaios, poesias, romances e contos. Foi doutora em letras e catedr\u00e1tica da Universidade Federal de Minas Gerais (UFMG) e professora visitante de universidades no exterior. Nascida em Belo Horizonte em 29 de maio de 1934, \u00e9 considerada uma das maiores escritoras da l\u00edngua portuguesa.<\/p>\n<p style=\"text-align: justify;\">Aos 26 anos, Maria Jos\u00e9 tornou-se a mais jovem professora catedr\u00e1tica do pa\u00eds e, por concurso, sucedeu o professor Eduardo Frieiro na Faculdade de Letras da UFMG, onde lecionou Literatura Hispano-Americana, e tamb\u00e9m concluiu o doutorado em Letras Neolatinas. Com uma longa e importante carreira como professora convidada em universidades da Europa e dos Estados Unidos, esteve em Sorbonne, Lille, Bordeaux, Aix-en-Provence, Bonn, Col\u00f4nia, Indiana, Harvard e Berkeley.<\/p>\n<p>Fonte: <em><a href=\"https:\/\/www.em.com.br\/cultura\/2023\/11\/6655643-morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz.html\">https:\/\/www.em.com.br\/cultura\/2023\/11\/6655643-morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz.html<\/a><\/em><\/p>","protected":false},"excerpt":{"rendered":"Morreu nesta quarta-feira (15\/11), aos 89 anos, a escritora mineira Maria Jos\u00e9 de Queiroz. O corpo ser\u00e1 velado na Academia Mineira de Letras a partir das 14h. Conhecida pela extensa","protected":false},"author":1,"featured_media":32853,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[53],"tags":[],"class_list":["post-32852","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-maria-jose-de-queiroz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Morre, aos 89 anos, a escritora mineira Maria Jos\u00e9 de Queiroz - Caravana Grupo Editorial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/caravanagrupoeditorial.com\/es_cl\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Morre, aos 89 anos, a escritora mineira Maria Jos\u00e9 de Queiroz - Caravana Grupo Editorial\" \/>\n<meta property=\"og:url\" content=\"https:\/\/caravanagrupoeditorial.com\/es_cl\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\/\" \/>\n<meta property=\"og:site_name\" content=\"Caravana Grupo Editorial\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/caravanagrupoeditorial\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-16T13:22:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-16T13:29:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/11\/1_maria_jose-32237083.jpg?fit=820%2C492&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"820\" \/>\n\t<meta property=\"og:image:height\" content=\"492\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Web Designer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Web Designer\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\\\/\"},\"author\":{\"name\":\"Web Designer\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#\\\/schema\\\/person\\\/abf39d87b39b20bc7acbebdea985becc\"},\"headline\":\"Morre, aos 89 anos, a escritora mineira Maria Jos\u00e9 de Queiroz\",\"datePublished\":\"2023-11-16T13:22:16+00:00\",\"dateModified\":\"2023-11-16T13:29:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\\\/\"},\"wordCount\":170,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/1_maria_jose-32237083.jpg?fit=820%2C492&ssl=1\",\"articleSection\":[\"Maria Jos\u00e9 de Queiroz\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/caravanagrupoeditorial.com\\\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\\\/\",\"url\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\\\/\",\"name\":\"Morre, aos 89 anos, a escritora mineira Maria Jos\u00e9 de Queiroz - Caravana Grupo Editorial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/1_maria_jose-32237083.jpg?fit=820%2C492&ssl=1\",\"datePublished\":\"2023-11-16T13:22:16+00:00\",\"dateModified\":\"2023-11-16T13:29:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/caravanagrupoeditorial.com\\\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/1_maria_jose-32237083.jpg?fit=820%2C492&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/1_maria_jose-32237083.jpg?fit=820%2C492&ssl=1\",\"width\":820,\"height\":492},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Morre, aos 89 anos, a escritora mineira Maria Jos\u00e9 de Queiroz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#website\",\"url\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/\",\"name\":\"Caravana Grupo Editorial\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#organization\",\"name\":\"Caravana Grupo Editorial\",\"url\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Logo_Caravana.png\",\"contentUrl\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Logo_Caravana.png\",\"width\":512,\"height\":512,\"caption\":\"Caravana Grupo Editorial\"},\"image\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/caravanagrupoeditorial\",\"https:\\\/\\\/www.instagram.com\\\/caravanagrupoeditorial\\\/?hl=pt-br\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCdD-xosEkpHCeRn2nDLiXfQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#\\\/schema\\\/person\\\/abf39d87b39b20bc7acbebdea985becc\",\"name\":\"Web Designer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g\",\"caption\":\"Web Designer\"},\"sameAs\":[\"https:\\\/\\\/caravanagrupoeditorial.com\"],\"url\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/es_cl\\\/author\\\/caravanagrupoedi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Morre, aos 89 anos, a escritora mineira Maria Jos\u00e9 de Queiroz - Caravana Grupo Editorial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/caravanagrupoeditorial.com\/es_cl\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\/","og_locale":"es_ES","og_type":"article","og_title":"Morre, aos 89 anos, a escritora mineira Maria Jos\u00e9 de Queiroz - Caravana Grupo Editorial","og_url":"https:\/\/caravanagrupoeditorial.com\/es_cl\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\/","og_site_name":"Caravana Grupo Editorial","article_publisher":"https:\/\/www.facebook.com\/caravanagrupoeditorial","article_published_time":"2023-11-16T13:22:16+00:00","article_modified_time":"2023-11-16T13:29:53+00:00","og_image":[{"width":820,"height":492,"url":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/11\/1_maria_jose-32237083.jpg?fit=820%2C492&ssl=1","type":"image\/jpeg"}],"author":"Web Designer","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Web Designer"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/caravanagrupoeditorial.com\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\/#article","isPartOf":{"@id":"https:\/\/caravanagrupoeditorial.com\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\/"},"author":{"name":"Web Designer","@id":"https:\/\/caravanagrupoeditorial.com\/#\/schema\/person\/abf39d87b39b20bc7acbebdea985becc"},"headline":"Morre, aos 89 anos, a escritora mineira Maria Jos\u00e9 de Queiroz","datePublished":"2023-11-16T13:22:16+00:00","dateModified":"2023-11-16T13:29:53+00:00","mainEntityOfPage":{"@id":"https:\/\/caravanagrupoeditorial.com\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\/"},"wordCount":170,"commentCount":0,"publisher":{"@id":"https:\/\/caravanagrupoeditorial.com\/#organization"},"image":{"@id":"https:\/\/caravanagrupoeditorial.com\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/11\/1_maria_jose-32237083.jpg?fit=820%2C492&ssl=1","articleSection":["Maria Jos\u00e9 de Queiroz"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/caravanagrupoeditorial.com\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/caravanagrupoeditorial.com\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\/","url":"https:\/\/caravanagrupoeditorial.com\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\/","name":"Morre, aos 89 anos, a escritora mineira Maria Jos\u00e9 de Queiroz - Caravana Grupo Editorial","isPartOf":{"@id":"https:\/\/caravanagrupoeditorial.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/caravanagrupoeditorial.com\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\/#primaryimage"},"image":{"@id":"https:\/\/caravanagrupoeditorial.com\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/11\/1_maria_jose-32237083.jpg?fit=820%2C492&ssl=1","datePublished":"2023-11-16T13:22:16+00:00","dateModified":"2023-11-16T13:29:53+00:00","breadcrumb":{"@id":"https:\/\/caravanagrupoeditorial.com\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/caravanagrupoeditorial.com\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/caravanagrupoeditorial.com\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\/#primaryimage","url":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/11\/1_maria_jose-32237083.jpg?fit=820%2C492&ssl=1","contentUrl":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/11\/1_maria_jose-32237083.jpg?fit=820%2C492&ssl=1","width":820,"height":492},{"@type":"BreadcrumbList","@id":"https:\/\/caravanagrupoeditorial.com\/morre-aos-89-anos-a-escritora-mineira-maria-jose-de-queiroz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/caravanagrupoeditorial.com\/"},{"@type":"ListItem","position":2,"name":"Morre, aos 89 anos, a escritora mineira Maria Jos\u00e9 de Queiroz"}]},{"@type":"WebSite","@id":"https:\/\/caravanagrupoeditorial.com\/#website","url":"https:\/\/caravanagrupoeditorial.com\/","name":"Cat\u00e1logo - Alicanto Editorial","description":"","publisher":{"@id":"https:\/\/caravanagrupoeditorial.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/caravanagrupoeditorial.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/caravanagrupoeditorial.com\/#organization","name":"Cat\u00e1logo - Alicanto Editorial","url":"https:\/\/caravanagrupoeditorial.com\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/caravanagrupoeditorial.com\/#\/schema\/logo\/image\/","url":"https:\/\/caravanagrupoeditorial.com\/wp-content\/uploads\/2024\/02\/cropped-Logo_Caravana.png","contentUrl":"https:\/\/caravanagrupoeditorial.com\/wp-content\/uploads\/2024\/02\/cropped-Logo_Caravana.png","width":512,"height":512,"caption":"Caravana Grupo Editorial"},"image":{"@id":"https:\/\/caravanagrupoeditorial.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/caravanagrupoeditorial","https:\/\/www.instagram.com\/caravanagrupoeditorial\/?hl=pt-br","https:\/\/www.youtube.com\/channel\/UCdD-xosEkpHCeRn2nDLiXfQ"]},{"@type":"Person","@id":"https:\/\/caravanagrupoeditorial.com\/#\/schema\/person\/abf39d87b39b20bc7acbebdea985becc","name":"Web Designer","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g","caption":"Web Designer"},"sameAs":["https:\/\/caravanagrupoeditorial.com"],"url":"https:\/\/caravanagrupoeditorial.com\/es_cl\/author\/caravanagrupoedi\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2023\/11\/1_maria_jose-32237083.jpg?fit=820%2C492&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/posts\/32852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/comments?post=32852"}],"version-history":[{"count":3,"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/posts\/32852\/revisions"}],"predecessor-version":[{"id":32858,"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/posts\/32852\/revisions\/32858"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/media\/32853"}],"wp:attachment":[{"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/media?parent=32852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/categories?post=32852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/caravanagrupoeditorial.com\/es_cl\/wp-json\/wp\/v2\/tags?post=32852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}