{"id":11615,"date":"2022-10-18T16:14:31","date_gmt":"2022-10-18T19:14:31","guid":{"rendered":"https:\/\/caravanagrupoeditorial.com\/?p=11615"},"modified":"2026-02-09T17:04:44","modified_gmt":"2026-02-09T20:04:44","slug":"o-homem-que-virou-sean-connery","status":"publish","type":"post","link":"https:\/\/caravanagrupoeditorial.com\/es\/o-homem-que-virou-sean-connery\/","title":{"rendered":"O homem que virou Sean Connery"},"content":{"rendered":"<p style=\"text-align: justify;\">No cruzamento da rua 45 com a 9\u00aa Avenida, em New York, algu\u00e9m grita: Ei! Sean Connery! Instintivamente, ele se vira para ver quem \u00e9. Um negro, com mais de um metro e noventa de altura, gorro de inverno na cabe\u00e7a, usando um sobretudo surrado, reminiscente da guerra do Vietn\u00e3, sorri para ele e completa: Voc\u00ea \u00e9 igual ao Sean! Mas voc\u00ea j\u00e1 sabia disso, n\u00e3o sabia? Solta uma sonora gargalhada, acena alegremente e some no meio da multid\u00e3o.<\/br>\n<\/br>\nCaminhando pela Bourbon Street, ele acompanha o gingado da m\u00fasica que escapa de todas as esquinas, bares, casas e vitrolas de New Orleans. Curioso, entra numa galeria de arte quando um senhor de meia idade se aproxima, olha fixamente para ele e diz: Desculpe, mas voc\u00ea \u00e9 a cara do Sean Connery! Ele sorri e agradece, porque toma a semelhan\u00e7a como um elogio.<\/br>\n<\/br>\nNo bar em Agoura Hills, condado de Los Angeles, ele renova o seu copo de u\u00edsque e vai para a \u00e1rea reservada aos fumantes. Acende seu charuto quando ouve um grupo de rapazes e mo\u00e7as gritarem em sua dire\u00e7\u00e3o: Ei, voc\u00ea \u00e9 igualzinho o Sean Connery! Cuspido e escarrado!, e saem cantando uma can\u00e7\u00e3o incompreens\u00edvel. No ambiente semi-escuro, ele se pergunta como \u00e9 poss\u00edvel confundir algu\u00e9m com algu\u00e9m naquela luz obtusa e mel\u00edflua.<\/br>\n<\/br>\nSentado em um caf\u00e9, na Pra\u00e7a da Savassi, em Belo Horizonte, ele espera o amigo chegar. Meia d\u00fazia de colegiais est\u00e3o reunidos na mureta do pequeno jardim. Olham para ele, sorriem, cochicham, at\u00e9 que uma garota se aproxima e pergunta se podem tirar uma foto com ele. Ele concorda e todos se penduram \u00e0 sua volta. Agradecem e retornam aos seus lugares. A mo\u00e7a mostra a foto no celular para os colegas e comenta: N\u00e3o disse que era parecido? Igualzinho, gente, igualzinho! Trocam sorrisos e de soslaio, olham para ele como se fossem cumplices de uma descoberta extraordin\u00e1ria.<\/br>\n<\/br>\nN\u00e3o foram poucas as vezes em que situa\u00e7\u00f5es como essas se repetiram. Em Paris, num bar da Rue de Mouffetard ou perdido entre os milhares de livros da Shakespeare &#038; Co., ou caminhando sob o sol de outono nas ramblas de Barcelona ou subindo a ladeira de Granada em dire\u00e7\u00e3o ao Alhambra ou perdido no labirinto do bairro judeu em Sevilha, ouvindo um fado trist\u00edssimo nos becos da Ribeira, no Porto ou no burburinho do cais de Sodr\u00e9 em Lisboa, pisando as velhas pedras e peda\u00e7os de hist\u00f3ria no Or\u00e1culo de Delfos na Gr\u00e9cia, nas ruinas gigantescas de Baalbek, no L\u00edbano, em dois ou tr\u00eas puteiros de S\u00e3o Paulo, num trem noturno para Madri, nas areias de uma praia em B\u00fazios, no adro da Igreja do Ros\u00e1rio, em Ouro Preto, ou em uma rua qualquer de Juiz de Fora, no interior de Minas, na noite de choro em um bar recendendo a cacha\u00e7a e bord\u00f5es de uma viola de sete cordas, sob os Arcos da Lapa&#8230; Sim, j\u00e1 tinha perdido a conta de quantas vezes e em quantos lugares ouvira dizer que ele era a cara de Sean Connery.<\/br>\n<\/br>\nSem que percebesse, passou a acreditar que era, realmente, s\u00f3sia do ator. Pensou que um dia, seria confundido com ele nas ruas de Londres ou de Edimburgo ou na casa do pr\u00f3prio ator, onde nem mesmo a criadagem notaria a diferen\u00e7a.<\/br>\n<\/br>\nA partir da\u00ed ficou possu\u00eddo pela ideia de se tornar Sean Connery, virar o outro, ser mais que s\u00f3sia, mais que seu duplo. Passou a ver todos os seus filmes, leu sua biografia, escarafunchou revistas, reportagens, entrevistas. J\u00e1 n\u00e3o havia um dia sequer que n\u00e3o se olhasse no espelho e n\u00e3o se achasse a cara de Sean Connery.<\/br>\n<\/br>\nPassou a reparar em seus sestros, olhares, esgares, o balan\u00e7o do corpo ao andar, pensou em fazer uma tatuagem imitando a cicatriz que o ator possu\u00eda no rosto, pr\u00f3ximo \u00e0 boca e que lhe emprestava aquele ar c\u00ednico de James Bond, com que enfrentava os advers\u00e1rios e as mulheres fatais.<\/br>\n<\/br>\nA coisa toda acabou se tornando uma obsess\u00e3o, uma esp\u00e9cie de loucura. Passou a sonhar encontrar Sean Connery em algum lugar do mundo e ter uma boa e convincente conversa com ele. A ideia era assumir o posto do ator em mais meia d\u00fazia de filmes, enquanto o verdadeiro Sean apareceria em p\u00fablico cada vez menos, descansando num dolce far niente em sua mans\u00e3o nas Bahamas, at\u00e9 que a vida se despedisse dele.<\/br>\n<\/br>\nApesar da diferen\u00e7a de idade, era 18 anos mais novo que Sean!, n\u00e3o via nisso\nnenhum empecilho \u00e0 sua ideia fixa de se beneficiar dessa semelhan\u00e7a. O problema era o talento do ator, mas se as tomadas fossem em plano geral ou m\u00e9dio, tudo correria bem, ele acreditava. Sou mais do que um &#8220;stunt man&#8221; e se falam tanto \u00e9 porque pare\u00e7o, dizia na frente do espelho. Ent\u00e3o, se decidiu. Comprou uma passagem s\u00f3 de ida para as Bahamas, onde Sean fora morar.<\/br>\n<\/br>\nReservou uma su\u00edte no British Colonial Hilton, em Nassau, e desembarcou vestido a car\u00e1ter. Era o Sean do filme \u201cO homem que queria ser rei\u201d. Deu tr\u00eas ou quatro aut\u00f3grafos para f\u00e3s desavisados, devolveu alguns cumprimentos e atirou na dire\u00e7\u00e3o do &#8220;conci\u00e8rge&#8221; seu nome e um sorriso malicioso que se refletiu no grande espelho que dominava o lobby.<\/br>\n<\/br>\nDe p\u00e9 em frente ao seu reflexo, ele se observa e observa o &#8220;conci\u00e8rge&#8221; que, sem tirar os olhos dele, cochicha ao telefone, com uma voz que soa entre cinismo e perplexidade, diz: Boa tarde, Sir! \u00c9 o William, do British Colonial. Tem um cavalheiro aqui dizendo que \u00e9 Sean Connery. A voz de Sean \u00e9 inconfund\u00edvel: OK, Bill. Provavelmente \u00e9. Diga a ele para esperar. Chego em 10 minutos&#8230;<\/p>\n\n\n\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"800\" src=\"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-18-at-14.08.29.jpeg?resize=801%2C800&#038;ssl=1\" alt=\"\" class=\"wp-image-11619 size-full\" srcset=\"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-18-at-14.08.29.jpeg?resize=801%2C800&amp;ssl=1 801w, https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-18-at-14.08.29.jpeg?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-18-at-14.08.29.jpeg?resize=280%2C280&amp;ssl=1 280w, https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-18-at-14.08.29.jpeg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-18-at-14.08.29.jpeg?resize=1536%2C1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-18-at-14.08.29.jpeg?resize=1320%2C1319&amp;ssl=1 1320w, https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-18-at-14.08.29.jpeg?resize=510%2C510&amp;ssl=1 510w, https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-18-at-14.08.29.jpeg?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2022\/10\/WhatsApp-Image-2022-10-18-at-14.08.29.jpeg?w=1600&amp;ssl=1 1600w\" sizes=\"auto, (max-width: 801px) 100vw, 801px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Nascido no Maranh\u00e3o, Tonico Mercador \u00e9 publicit\u00e1rio. Tornou-se ativo colaborador do Suplemento Liter\u00e1rio do Minas Gerais. Publicou\u00a0<em>Itiner\u00e1rio da Era do Rock<\/em>,\u00a0<em>Iluminuras<\/em>,\u00a0<em>Perversos,<\/em>\u00a0<em>Olhos quase cegos<\/em>,\u00a0<em>O Invasor de Livros,\u00a0<\/em>dentre outros. Foi presidente da Associa\u00e7\u00e3o Profissional dos Escritores de Minas Gerais e diretor de reda\u00e7\u00e3o da revista Palavra. Pela Caravana Grupo Editorial, publicou\u00a0<em>O Invasor de livros<\/em>\u00a0e\u00a0<em>Cantos de sil\u00eancio e aus\u00eancia<\/em>, ambos em 2019. Em 2020, a Caravana lan\u00e7a\u00a0<em>Tonico Mercador, 50 anos de poesia<\/em>.<\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>No cruzamento da rua 45 com a 9\u00aa Avenida, em New York, algu\u00e9m grita: Ei! Sean Connery! Instintivamente, ele se vira para ver quem \u00e9. Um negro, com mais de<\/p>","protected":false},"author":1,"featured_media":11618,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[20603,193],"tags":[],"class_list":["post-11615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronicas-editoriais","category-sem-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O homem que virou Sean Connery - Caravana Grupo Editorial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/caravanagrupoeditorial.com\/es\/o-homem-que-virou-sean-connery\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O homem que virou Sean Connery - Caravana Grupo Editorial\" \/>\n<meta property=\"og:description\" content=\"No cruzamento da rua 45 com a 9\u00aa Avenida, em New York, algu\u00e9m grita: Ei! Sean Connery! Instintivamente, ele se vira para ver quem \u00e9. Um negro, com mais de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/caravanagrupoeditorial.com\/es\/o-homem-que-virou-sean-connery\/\" \/>\n<meta property=\"og:site_name\" content=\"Caravana Grupo Editorial\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/caravanagrupoeditorial\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-18T19:14:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T20:04:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2022\/10\/tonico-mercador.jpeg?fit=1080%2C1080&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Web Designer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Web Designer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/o-homem-que-virou-sean-connery\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/o-homem-que-virou-sean-connery\\\/\"},\"author\":{\"name\":\"Web Designer\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#\\\/schema\\\/person\\\/abf39d87b39b20bc7acbebdea985becc\"},\"headline\":\"O homem que virou Sean Connery\",\"datePublished\":\"2022-10-18T19:14:31+00:00\",\"dateModified\":\"2026-02-09T20:04:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/o-homem-que-virou-sean-connery\\\/\"},\"wordCount\":1076,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/o-homem-que-virou-sean-connery\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/tonico-mercador.jpeg?fit=1080%2C1080&ssl=1\",\"articleSection\":[\"Cr\u00f4nicas editoriais\",\"Sem categoria\"],\"inLanguage\":\"es-PE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/caravanagrupoeditorial.com\\\/o-homem-que-virou-sean-connery\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/o-homem-que-virou-sean-connery\\\/\",\"url\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/o-homem-que-virou-sean-connery\\\/\",\"name\":\"O homem que virou Sean Connery - Caravana Grupo Editorial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/o-homem-que-virou-sean-connery\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/o-homem-que-virou-sean-connery\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/tonico-mercador.jpeg?fit=1080%2C1080&ssl=1\",\"datePublished\":\"2022-10-18T19:14:31+00:00\",\"dateModified\":\"2026-02-09T20:04:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/o-homem-que-virou-sean-connery\\\/#breadcrumb\"},\"inLanguage\":\"es-PE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/caravanagrupoeditorial.com\\\/o-homem-que-virou-sean-connery\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-PE\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/o-homem-que-virou-sean-connery\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/tonico-mercador.jpeg?fit=1080%2C1080&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/tonico-mercador.jpeg?fit=1080%2C1080&ssl=1\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/o-homem-que-virou-sean-connery\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O homem que virou Sean Connery\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#website\",\"url\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/\",\"name\":\"Caravana Grupo Editorial\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-PE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#organization\",\"name\":\"Caravana Grupo Editorial\",\"url\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-PE\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Logo_Caravana.png\",\"contentUrl\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Logo_Caravana.png\",\"width\":512,\"height\":512,\"caption\":\"Caravana Grupo Editorial\"},\"image\":{\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/caravanagrupoeditorial\",\"https:\\\/\\\/www.instagram.com\\\/caravanagrupoeditorial\\\/?hl=pt-br\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCdD-xosEkpHCeRn2nDLiXfQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/#\\\/schema\\\/person\\\/abf39d87b39b20bc7acbebdea985becc\",\"name\":\"Web Designer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-PE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g\",\"caption\":\"Web Designer\"},\"sameAs\":[\"https:\\\/\\\/caravanagrupoeditorial.com\"],\"url\":\"https:\\\/\\\/caravanagrupoeditorial.com\\\/es\\\/author\\\/caravanagrupoedi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O homem que virou Sean Connery - Caravana Grupo Editorial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/caravanagrupoeditorial.com\/es\/o-homem-que-virou-sean-connery\/","og_locale":"es_ES","og_type":"article","og_title":"O homem que virou Sean Connery - Caravana Grupo Editorial","og_description":"No cruzamento da rua 45 com a 9\u00aa Avenida, em New York, algu\u00e9m grita: Ei! Sean Connery! Instintivamente, ele se vira para ver quem \u00e9. Um negro, com mais de","og_url":"https:\/\/caravanagrupoeditorial.com\/es\/o-homem-que-virou-sean-connery\/","og_site_name":"Caravana Grupo Editorial","article_publisher":"https:\/\/www.facebook.com\/caravanagrupoeditorial","article_published_time":"2022-10-18T19:14:31+00:00","article_modified_time":"2026-02-09T20:04:44+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2022\/10\/tonico-mercador.jpeg?fit=1080%2C1080&ssl=1","type":"image\/jpeg"}],"author":"Web Designer","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Web Designer","Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/caravanagrupoeditorial.com\/o-homem-que-virou-sean-connery\/#article","isPartOf":{"@id":"https:\/\/caravanagrupoeditorial.com\/o-homem-que-virou-sean-connery\/"},"author":{"name":"Web Designer","@id":"https:\/\/caravanagrupoeditorial.com\/#\/schema\/person\/abf39d87b39b20bc7acbebdea985becc"},"headline":"O homem que virou Sean Connery","datePublished":"2022-10-18T19:14:31+00:00","dateModified":"2026-02-09T20:04:44+00:00","mainEntityOfPage":{"@id":"https:\/\/caravanagrupoeditorial.com\/o-homem-que-virou-sean-connery\/"},"wordCount":1076,"commentCount":2,"publisher":{"@id":"https:\/\/caravanagrupoeditorial.com\/#organization"},"image":{"@id":"https:\/\/caravanagrupoeditorial.com\/o-homem-que-virou-sean-connery\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2022\/10\/tonico-mercador.jpeg?fit=1080%2C1080&ssl=1","articleSection":["Cr\u00f4nicas editoriais","Sem categoria"],"inLanguage":"es-PE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/caravanagrupoeditorial.com\/o-homem-que-virou-sean-connery\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/caravanagrupoeditorial.com\/o-homem-que-virou-sean-connery\/","url":"https:\/\/caravanagrupoeditorial.com\/o-homem-que-virou-sean-connery\/","name":"O homem que virou Sean Connery - Caravana Grupo Editorial","isPartOf":{"@id":"https:\/\/caravanagrupoeditorial.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/caravanagrupoeditorial.com\/o-homem-que-virou-sean-connery\/#primaryimage"},"image":{"@id":"https:\/\/caravanagrupoeditorial.com\/o-homem-que-virou-sean-connery\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2022\/10\/tonico-mercador.jpeg?fit=1080%2C1080&ssl=1","datePublished":"2022-10-18T19:14:31+00:00","dateModified":"2026-02-09T20:04:44+00:00","breadcrumb":{"@id":"https:\/\/caravanagrupoeditorial.com\/o-homem-que-virou-sean-connery\/#breadcrumb"},"inLanguage":"es-PE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/caravanagrupoeditorial.com\/o-homem-que-virou-sean-connery\/"]}]},{"@type":"ImageObject","inLanguage":"es-PE","@id":"https:\/\/caravanagrupoeditorial.com\/o-homem-que-virou-sean-connery\/#primaryimage","url":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2022\/10\/tonico-mercador.jpeg?fit=1080%2C1080&ssl=1","contentUrl":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2022\/10\/tonico-mercador.jpeg?fit=1080%2C1080&ssl=1","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/caravanagrupoeditorial.com\/o-homem-que-virou-sean-connery\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/caravanagrupoeditorial.com\/"},{"@type":"ListItem","position":2,"name":"O homem que virou Sean Connery"}]},{"@type":"WebSite","@id":"https:\/\/caravanagrupoeditorial.com\/#website","url":"https:\/\/caravanagrupoeditorial.com\/","name":"Cat\u00e1logo - Kuntur Editorial","description":"","publisher":{"@id":"https:\/\/caravanagrupoeditorial.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/caravanagrupoeditorial.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-PE"},{"@type":"Organization","@id":"https:\/\/caravanagrupoeditorial.com\/#organization","name":"Cat\u00e1logo - Kuntur Editorial","url":"https:\/\/caravanagrupoeditorial.com\/","logo":{"@type":"ImageObject","inLanguage":"es-PE","@id":"https:\/\/caravanagrupoeditorial.com\/#\/schema\/logo\/image\/","url":"https:\/\/caravanagrupoeditorial.com\/wp-content\/uploads\/2024\/02\/cropped-Logo_Caravana.png","contentUrl":"https:\/\/caravanagrupoeditorial.com\/wp-content\/uploads\/2024\/02\/cropped-Logo_Caravana.png","width":512,"height":512,"caption":"Caravana Grupo Editorial"},"image":{"@id":"https:\/\/caravanagrupoeditorial.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/caravanagrupoeditorial","https:\/\/www.instagram.com\/caravanagrupoeditorial\/?hl=pt-br","https:\/\/www.youtube.com\/channel\/UCdD-xosEkpHCeRn2nDLiXfQ"]},{"@type":"Person","@id":"https:\/\/caravanagrupoeditorial.com\/#\/schema\/person\/abf39d87b39b20bc7acbebdea985becc","name":"Web Designer","image":{"@type":"ImageObject","inLanguage":"es-PE","@id":"https:\/\/secure.gravatar.com\/avatar\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7be9c0222f263eb34acb5623f9380ff97b339f48774cd9131eca6db48413710?s=96&d=mm&r=g","caption":"Web Designer"},"sameAs":["https:\/\/caravanagrupoeditorial.com"],"url":"https:\/\/caravanagrupoeditorial.com\/es\/author\/caravanagrupoedi\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/caravanagrupoeditorial.com\/wp-content\/uploads\/2022\/10\/tonico-mercador.jpeg?fit=1080%2C1080&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/caravanagrupoeditorial.com\/es\/wp-json\/wp\/v2\/posts\/11615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/caravanagrupoeditorial.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/caravanagrupoeditorial.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/caravanagrupoeditorial.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/caravanagrupoeditorial.com\/es\/wp-json\/wp\/v2\/comments?post=11615"}],"version-history":[{"count":4,"href":"https:\/\/caravanagrupoeditorial.com\/es\/wp-json\/wp\/v2\/posts\/11615\/revisions"}],"predecessor-version":[{"id":11626,"href":"https:\/\/caravanagrupoeditorial.com\/es\/wp-json\/wp\/v2\/posts\/11615\/revisions\/11626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/caravanagrupoeditorial.com\/es\/wp-json\/wp\/v2\/media\/11618"}],"wp:attachment":[{"href":"https:\/\/caravanagrupoeditorial.com\/es\/wp-json\/wp\/v2\/media?parent=11615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/caravanagrupoeditorial.com\/es\/wp-json\/wp\/v2\/categories?post=11615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/caravanagrupoeditorial.com\/es\/wp-json\/wp\/v2\/tags?post=11615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}